
{"id":1008,"date":"2017-07-01T10:52:01","date_gmt":"2017-07-01T09:52:01","guid":{"rendered":"https:\/\/blog.madeleinemeuwessen.nl\/?p=1008"},"modified":"2017-07-01T10:52:01","modified_gmt":"2017-07-01T09:52:01","slug":"peer-giesser-uomo-selvaggio","status":"publish","type":"post","link":"https:\/\/blog.madeleinemeuwessen.nl\/it\/2017\/07\/01\/peer-giesser-wildeman\/","title":{"rendered":"PEER (uomo selvatico di Giesser)"},"content":{"rendered":"<p>Una citazione di un cliente:<strong> Peer non si preoccupa pi\u00f9!<img decoding=\"async\" class=\"alignright size-full wp-image-1021\" src=\"https:\/\/blog.madeleinemeuwessen.nl\/wp-content\/uploads\/2017\/07\/peer.jpg\" alt=\"\" width=\"400\" height=\"300\" srcset=\"https:\/\/blog.madeleinemeuwessen.nl\/wp-content\/uploads\/2017\/07\/peer.jpg 400w, https:\/\/blog.madeleinemeuwessen.nl\/wp-content\/uploads\/2017\/07\/peer-300x225.jpg 300w\" sizes=\"(max-width: 400px) 100vw, 400px\" \/><\/strong><\/p>\n<p>In primavera, l'albero si trasforma in un bellissimo rimedio per le pere in fiore e in inverno mi godo queste deliziose pere da stufare!<\/p>\n<p>Pear \u00e8 il rimedio floreale per coloro che, dopo molti fallimenti, hanno perso il coraggio in una situazione apparentemente senza speranza. Pear aiuta anche in caso di malattie di lunga durata, in cui non c'\u00e8 speranza di guarigione e il paziente non crede pi\u00f9 nella salvezza.<\/p>\n<p>Se avete incontrato difficolt\u00e0 molte volte nella vostra vita e al prossimo ostacolo pensate gi\u00e0: probabilmente andr\u00e0 male di nuovo, Peer vi aiuter\u00e0 a portare a termine il lavoro. Se soffrite di depressione, se siete stati bocciati molte volte agli esami, se siete finiti in una palude oscura o se tutto vi sembra senza speranza.<\/p>\n<p>Queste persone soffrono davvero di una profonda disperazione, tutto appare loro desolante e vuoto. Hanno gi\u00e0 fatto molti tentativi e hanno sperimentato cos\u00ec tante delusioni che non vogliono pi\u00f9 andare avanti. Ogni ulteriore sforzo sembra loro inutile, tanto non c'\u00e8 nessun altro che possa aiutarli. Non si lamentano nemmeno pi\u00f9 della loro sofferenza, perch\u00e9 anche questo sembra loro inutile. Spesso i familiari li convincono a fare un altro tentativo, ma solo per compiacerli. Dentro di s\u00e9, sono convinti in anticipo che l'impresa non porter\u00e0 a nulla.<br \/>\nSpesso hanno una carnagione pallida e occhiaie.<\/p>\n<p>Ricordate il blog precedente che ho dedicato al rimedio dei fiori di Bali? A volte \u00e8 difficile stabilire con esattezza se si soffre dello stato d'animo negativo di Bali o di Peer. Una sorta di ponte dell'asino \u00e8 che le persone Bali \"sentono\" che la loro situazione \u00e8 senza speranza e con Pear la mente dice che niente, ma proprio niente, pu\u00f2 pi\u00f9 aiutarle.<\/p>\n<p>Un buon esempio: si tratta di un uomo di 37 anni che vive da diversi anni con la sua compagna, senza figli.<br \/>\nL'uomo occupa una posizione di rilievo in un'azienda statunitense.<br \/>\nMi consegna un rapporto di due psicologi che lo hanno sottoposto a un test per conto del suo datore di lavoro.<br \/>\nLavora in questa azienda da 13 anni. Ogni volta \u00e8 salito un gradino pi\u00f9 in alto nella scala.<\/p>\n<p>Non ha alcun disturbo fisico (dice), ma soffre di vertigini, mal di testa, dolori muscolari, dolori al collo e alla schiena, ha problemi a dormire, non riesce a rilassarsi ed \u00e8 irritabile.<br \/>\nNell'ultimo mese ha avuto 2 volte sintomi di panico accompagnati da respiro corto, palpitazioni, paura di perdere il controllo e sudorazione.<br \/>\nSecondo lui non si tratta di veri e propri disturbi fisici, ma di una sensazione di disagio nella propria pelle. Non ricorda quando \u00e8 iniziata questa sensazione, circa cinque anni fa, ma sa che si \u00e8 insinuata lentamente.<br \/>\nSpesso sente di essere alla ricerca di qualcosa che cambier\u00e0 la sua vita, ma per Dio non sa cosa. Si sente mentalmente stanco e il suo rendimento \u00e8 compromesso. Tende a evitare alcune situazioni movimentate, come fare la fila in un negozio, perch\u00e9 sente di essere osservato. Ha anche difficolt\u00e0 a uscire da solo, perch\u00e9 prova sentimenti di imbarazzo. Indica che i suoi disturbi sono legati al lavoro. Negli ultimi due mesi non ha lavorato affatto.<br \/>\n<em>Secondo il rapporto:<br \/>\nDiagnosi secondo il DSM-IV<br \/>\nAsI: 300.81 Disturbo somatoforme indifferenziato (burnout)<br \/>\nAsse II: -<br \/>\nAsse III: mal di schiena<br \/>\nAsse IV: stress da lavoro: alto<br \/>\nAsse V: punteggio Gaf:<\/em><\/p>\n<p><em>Proposta di terapia:<\/em><br \/>\n<em> Terapia cognitivo-comportamentale secondo il protocollo del burnout, con particolare attenzione al training di rilassamento, alla gestione dello stress e all'identificazione e modifica delle cognizioni disfunzionali nel campo del perfezionismo, tra le altre cose. Inoltre, se i sintomi del panico non diminuiscono a sufficienza, bisogna prestare attenzione a questo aspetto attraverso la terapia cognitiva e gli esercizi di esposizione.<\/em><br \/>\n<em> Guidare la ripresa del lavoro.<\/em><\/p>\n<p>Per me la cosa pi\u00f9 importante all'inizio \u00e8 stata che, nonostante avesse detto di aver perso ogni speranza, \u00e8 venuto da me letteralmente \"per mano\" di sua sorella. Questo significa che da qualche parte sperava in un miracolo e voleva \"affrontare\" la terapia.<\/p>\n<p>Perch\u00e9 non ho mai dimenticato questo cliente? Beh, dai suoi abiti di Armani!<br \/>\nUna volta che ci siamo messi al lavoro, una delle prime cose che ha fatto \u00e8 stata quella di dare i suoi abiti di Armani (di cui andava molto fiero) alla sua collaboratrice domestica. Non ne aveva pi\u00f9 bisogno. Dopodich\u00e9, lui e la sua ragazza si sono lasciati in buoni rapporti.<br \/>\nAlla fine ha detto addio all'azienda per cui lavorava. Si \u00e8 messo in proprio in un settore completamente diverso... e ha avuto molto successo! Si \u00e8 sposato con l'amore della sua vita e insieme hanno due figlie piccole. Ed \u00e8 diventato, nonostante le cose che ti capitano sempre a tiro, un uomo molto felice.<br \/>\nSe avessi \"trascurato\" lo stato d'animo di Peer, si sarebbe verificato un blocco e l'intero trattamento avrebbe potuto richiedere molto pi\u00f9 tempo.<\/p>\n<p>Il terapeuta non ha esattamente vita facile con i suoi collaboratori Peer. Inoltre, cosa si dovrebbe fare con una persona che non crede pi\u00f9 nella guarigione o nell'alleviamento dei suoi sintomi e non viene nemmeno da te di sua spontanea volont\u00e0?<br \/>\nLe difese interiori delle persone sono il pi\u00f9 grande ostacolo sulla strada della salute. In qualit\u00e0 di terapeuti, potreste avere la sensazione che il trattamento serva solo come alibi<br \/>\nserve e il fallimento (previsto) per la famiglia dovrebbe servire come prova dell'incurabilit\u00e0 della malattia. Pertanto, il fallimento di qualsiasi terapia \u00e8 incluso nel programma in anticipo.<\/p>\n<p>Se, contrariamente alle aspettative, si verifica un miglioramento, seppur modesto, la terapia viene interrotta con la motivazione che un progresso cos\u00ec scarso non vale lo sforzo. Dopo tutto, il paziente si era gi\u00e0 rassegnato a dover sopportare i suoi sintomi fino alla fine della sua vita.<br \/>\nE ora il rimedio floreale Pear pu\u00f2 aiutare a rimuovere il blocco interiore in modo che il cliente si apra al trattamento. L'attaccamento interiore alla malattia \u00e8 in definitiva la causa dell'incurabilit\u00e0. Pear funziona in questi casi come un \"agente persuasivo\" psichico ed \u00e8 assolutamente necessario utilizzarlo con tutti i disturbi cronico-degenerativi in cui si \u00e8 instaurato un ristagno nella guarigione e il successo del trattamento sta ristagnando.<\/p>\n<p>Per le persone a cui \u00e8 stata diagnosticata una malattia incurabile o che si sentono senza speranza nella loro vita, il rimedio floreale Pear pu\u00f2 avere un significato enorme.<br \/>\n<strong>Vorrei sottolineare con forza che questo rimedio non pu\u00f2 curare la malattia, quindi non ci sono assolutamente false o errate aspettative. Personalmente vedo questo rimedio come un aiuto attraverso il quale le persone riacquistano una maniglia e una speranza per combattere la loro malattia o la loro disperazione.<\/strong><\/p>\n<p>Il rimedio del fiore della pera vi d\u00e0 la forza interiore e vi restituisce la fiducia in voi stessi. Se affermate a voi stessi che potete farcela, potete farcela.<\/p>\n<p>La pera ti restituisce la sensazione di scintillio che hai dentro. La \"sensazione di felicit\u00e0\", come la chiamo sempre io. Sapere, anche dalla vostra mente razionale, che ora le cose andranno bene. Potete riabbracciare la vita con piena fiducia, perch\u00e9 vi \"restituisce\" la vostra vera fiducia interiore nella vita.<\/p>\n<p>Vogliamo farlo nell'acqua potabile dei Paesi Bassi?<\/p>\n<p>Madeleine Meuwessen<\/p>\n<p>*I rimedi floreali non sostituiscono i farmaci. In caso di dubbio, si consiglia di consultare sempre un medico.<\/p>","protected":false},"excerpt":{"rendered":"<p>Een uitspraak van een cli\u00ebnt: Peer doet niet moeilijk meer! In het voorjaar maak ik van de boom de prachtige bloesemremedie Peer en in de winter geniet ik van deze heerlijke stoofperen! Peer is de bloesemremedie voor hen die na vele fiasco&#8217;s de moed in een schijnbaar uitzichtloze situatie kwijt zijn. Ook bij langdurige ziekten, [&#8230;]\n","protected":false},"author":4,"featured_media":1021,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3],"tags":[361,363,362,360,364,357,358,356,132,359],"class_list":["post-1008","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-star-remedies","tag-bleke-gelaatskleur","tag-diepe-neerslachtigheid","tag-donkere-kringen-onder-ogen","tag-hopeloosheid","tag-klachten-linkerzijde-van-de-nek","tag-machteloos","tag-niemand-kan-me-helpen","tag-somber","tag-vermoeidheid","tag-voel-me-verloren"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>PEER (Giesser wildeman) - Madeleine Meuwessen<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/blog.madeleinemeuwessen.nl\/it\/2017\/07\/01\/peer-giesser-uomo-selvaggio\/\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"PEER (Giesser wildeman) - Madeleine Meuwessen\" \/>\n<meta property=\"og:description\" content=\"Een uitspraak van een cli\u00ebnt: Peer doet niet moeilijk meer! In het voorjaar maak ik van de boom de prachtige bloesemremedie Peer en in de winter geniet ik van deze heerlijke stoofperen! Peer is de bloesemremedie voor hen die na vele fiasco&#8217;s de moed in een schijnbaar uitzichtloze situatie kwijt zijn. Ook bij langdurige ziekten, [...]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.madeleinemeuwessen.nl\/it\/2017\/07\/01\/peer-giesser-uomo-selvaggio\/\" \/>\n<meta property=\"og:site_name\" content=\"Madeleine Meuwessen\" \/>\n<meta property=\"article:published_time\" content=\"2017-07-01T09:52:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/blog.madeleinemeuwessen.nl\/wp-content\/uploads\/2017\/07\/peer.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"400\" \/>\n\t<meta property=\"og:image:height\" content=\"300\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"M. Meuwessen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"M. Meuwessen\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minuti\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/\"},\"author\":{\"name\":\"M. Meuwessen\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/#\\\/schema\\\/person\\\/bec97814dfe7825a10b34fdd36706181\"},\"headline\":\"PEER (Giesser wildeman)\",\"datePublished\":\"2017-07-01T09:52:01+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/\"},\"wordCount\":1248,\"image\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/peer.jpg\",\"keywords\":[\"bleke gelaatskleur\",\"diepe neerslachtigheid\",\"donkere kringen onder ogen\",\"hopeloosheid\",\"klachten linkerzijde van de nek\",\"machteloos\",\"niemand kan me helpen\",\"somber\",\"vermoeidheid\",\"voel me verloren\"],\"articleSection\":[\"Star Remedies\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/\",\"url\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/\",\"name\":\"PEER (Giesser wildeman) - Madeleine Meuwessen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/peer.jpg\",\"datePublished\":\"2017-07-01T09:52:01+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/#\\\/schema\\\/person\\\/bec97814dfe7825a10b34fdd36706181\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/#primaryimage\",\"url\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/peer.jpg\",\"contentUrl\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/wp-content\\\/uploads\\\/2017\\\/07\\\/peer.jpg\",\"width\":400,\"height\":300},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/2017\\\/07\\\/01\\\/peer-giesser-wildeman\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"PEER (Giesser wildeman)\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/#website\",\"url\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/\",\"name\":\"Madeleine Meuwessen\",\"description\":\"Als je het leven snapt, begrijp je de wereld niet.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/#\\\/schema\\\/person\\\/bec97814dfe7825a10b34fdd36706181\",\"name\":\"M. Meuwessen\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68bd9698b79bd41856398124d4d3b7223cd303eb0bdd076d414648658c3a48d6?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68bd9698b79bd41856398124d4d3b7223cd303eb0bdd076d414648658c3a48d6?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/68bd9698b79bd41856398124d4d3b7223cd303eb0bdd076d414648658c3a48d6?s=96&d=mm&r=g\",\"caption\":\"M. Meuwessen\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"PEER (uomo selvatico di Giesser) - Madeleine Meuwessen","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/blog.madeleinemeuwessen.nl\/it\/2017\/07\/01\/peer-giesser-uomo-selvaggio\/","og_locale":"it_IT","og_type":"article","og_title":"PEER (Giesser wildeman) - Madeleine Meuwessen","og_description":"Een uitspraak van een cli\u00ebnt: Peer doet niet moeilijk meer! In het voorjaar maak ik van de boom de prachtige bloesemremedie Peer en in de winter geniet ik van deze heerlijke stoofperen! Peer is de bloesemremedie voor hen die na vele fiasco&#8217;s de moed in een schijnbaar uitzichtloze situatie kwijt zijn. Ook bij langdurige ziekten, [...]","og_url":"https:\/\/blog.madeleinemeuwessen.nl\/it\/2017\/07\/01\/peer-giesser-uomo-selvaggio\/","og_site_name":"Madeleine Meuwessen","article_published_time":"2017-07-01T09:52:01+00:00","og_image":[{"width":400,"height":300,"url":"https:\/\/blog.madeleinemeuwessen.nl\/wp-content\/uploads\/2017\/07\/peer.jpg","type":"image\/jpeg"}],"author":"M. Meuwessen","twitter_card":"summary_large_image","twitter_misc":{"Scritto da":"M. Meuwessen","Tempo di lettura stimato":"6 minuti"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/#article","isPartOf":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/"},"author":{"name":"M. Meuwessen","@id":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/#\/schema\/person\/bec97814dfe7825a10b34fdd36706181"},"headline":"PEER (Giesser wildeman)","datePublished":"2017-07-01T09:52:01+00:00","mainEntityOfPage":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/"},"wordCount":1248,"image":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.madeleinemeuwessen.nl\/wp-content\/uploads\/2017\/07\/peer.jpg","keywords":["bleke gelaatskleur","diepe neerslachtigheid","donkere kringen onder ogen","hopeloosheid","klachten linkerzijde van de nek","machteloos","niemand kan me helpen","somber","vermoeidheid","voel me verloren"],"articleSection":["Star Remedies"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/","url":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/","name":"PEER (uomo selvatico di Giesser) - Madeleine Meuwessen","isPartOf":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/#website"},"primaryImageOfPage":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/#primaryimage"},"image":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/#primaryimage"},"thumbnailUrl":"https:\/\/blog.madeleinemeuwessen.nl\/wp-content\/uploads\/2017\/07\/peer.jpg","datePublished":"2017-07-01T09:52:01+00:00","author":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/#\/schema\/person\/bec97814dfe7825a10b34fdd36706181"},"breadcrumb":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/#primaryimage","url":"https:\/\/blog.madeleinemeuwessen.nl\/wp-content\/uploads\/2017\/07\/peer.jpg","contentUrl":"https:\/\/blog.madeleinemeuwessen.nl\/wp-content\/uploads\/2017\/07\/peer.jpg","width":400,"height":300},{"@type":"BreadcrumbList","@id":"https:\/\/blog.madeleinemeuwessen.nl\/2017\/07\/01\/peer-giesser-wildeman\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.madeleinemeuwessen.nl\/"},{"@type":"ListItem","position":2,"name":"PEER (Giesser wildeman)"}]},{"@type":"WebSite","@id":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/#website","url":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/","name":"Madeleine Meuwessen","description":"Se si capisce la vita, non si capisce il mondo.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Person","@id":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/#\/schema\/person\/bec97814dfe7825a10b34fdd36706181","name":"M. Meuwessen","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/68bd9698b79bd41856398124d4d3b7223cd303eb0bdd076d414648658c3a48d6?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/68bd9698b79bd41856398124d4d3b7223cd303eb0bdd076d414648658c3a48d6?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/68bd9698b79bd41856398124d4d3b7223cd303eb0bdd076d414648658c3a48d6?s=96&d=mm&r=g","caption":"M. Meuwessen"}}]}},"_links":{"self":[{"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/posts\/1008","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/comments?post=1008"}],"version-history":[{"count":5,"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/posts\/1008\/revisions"}],"predecessor-version":[{"id":1026,"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/posts\/1008\/revisions\/1026"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/media\/1021"}],"wp:attachment":[{"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/media?parent=1008"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/categories?post=1008"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog.madeleinemeuwessen.nl\/it\/wp-json\/wp\/v2\/tags?post=1008"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}