
{"id":206,"count":1,"description":"","link":"https:\/\/blog.madeleinemeuwessen.nl\/en\/tag\/pensionering\/","name":"retirement","slug":"pensionering","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>pensionering Archieven - Madeleine Meuwessen<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"en_GB\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"pensionering Archieven - Madeleine Meuwessen\" \/>\n<meta property=\"og:url\" content=\"https:\/\/blog.madeleinemeuwessen.nl\/en\/tag\/pensionering\/\" \/>\n<meta property=\"og:site_name\" content=\"Madeleine Meuwessen\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/tag\\\/pensionering\\\/\",\"url\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/tag\\\/pensionering\\\/\",\"name\":\"pensionering Archieven - Madeleine Meuwessen\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/tag\\\/pensionering\\\/#breadcrumb\"},\"inLanguage\":\"en-GB\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/tag\\\/pensionering\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"pensionering\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/#website\",\"url\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/\",\"name\":\"Madeleine Meuwessen\",\"description\":\"Als je het leven snapt, begrijp je de wereld niet.\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/blog.madeleinemeuwessen.nl\\\/ko\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-GB\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"pensionering Archieven - Madeleine Meuwessen","robots":{"index":"noindex","follow":"follow"},"og_locale":"en_GB","og_type":"article","og_title":"pensionering Archieven - Madeleine Meuwessen","og_url":"https:\/\/blog.madeleinemeuwessen.nl\/en\/tag\/pensionering\/","og_site_name":"Madeleine Meuwessen","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/blog.madeleinemeuwessen.nl\/tag\/pensionering\/","url":"https:\/\/blog.madeleinemeuwessen.nl\/tag\/pensionering\/","name":"Retirement Archives - Madeleine Meuwessen","isPartOf":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/#website"},"breadcrumb":{"@id":"https:\/\/blog.madeleinemeuwessen.nl\/tag\/pensionering\/#breadcrumb"},"inLanguage":"en-GB"},{"@type":"BreadcrumbList","@id":"https:\/\/blog.madeleinemeuwessen.nl\/tag\/pensionering\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/blog.madeleinemeuwessen.nl\/"},{"@type":"ListItem","position":2,"name":"pensionering"}]},{"@type":"WebSite","@id":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/#website","url":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/","name":"Madeleine Meuwessen","description":"If you understand life, you don't understand the world.","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/blog.madeleinemeuwessen.nl\/ko\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-GB"}]}},"_links":{"self":[{"href":"https:\/\/blog.madeleinemeuwessen.nl\/en\/wp-json\/wp\/v2\/tags\/206","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog.madeleinemeuwessen.nl\/en\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/blog.madeleinemeuwessen.nl\/en\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/blog.madeleinemeuwessen.nl\/en\/wp-json\/wp\/v2\/posts?tags=206"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}